{"id":1730,"count":2,"description":"","link":"http:\/\/sunplanetdealz.com\/index.php\/categoria-producto\/discos-duros-solidos-externos\/","name":"Discos duros s\u00f3lidos externos","slug":"discos-duros-solidos-externos","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Discos duros s\u00f3lidos externos archivos - Ofertas para el Verano en Sunplanetdealz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/sunplanetdealz.com\/index.php\/categoria-producto\/discos-duros-solidos-externos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Discos duros s\u00f3lidos externos archivos - Ofertas para el Verano en Sunplanetdealz\" \/>\n<meta property=\"og:url\" content=\"http:\/\/sunplanetdealz.com\/index.php\/categoria-producto\/discos-duros-solidos-externos\/\" \/>\n<meta property=\"og:site_name\" content=\"Ofertas para el Verano en Sunplanetdealz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\\\/\\\/sunplanetdealz.com\\\/index.php\\\/categoria-producto\\\/discos-duros-solidos-externos\\\/\",\"url\":\"http:\\\/\\\/sunplanetdealz.com\\\/index.php\\\/categoria-producto\\\/discos-duros-solidos-externos\\\/\",\"name\":\"Discos duros s\u00f3lidos externos archivos - Ofertas para el Verano en Sunplanetdealz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sunplanetdealz.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/sunplanetdealz.com\\\/index.php\\\/categoria-producto\\\/discos-duros-solidos-externos\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/sunplanetdealz.com\\\/index.php\\\/categoria-producto\\\/discos-duros-solidos-externos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/sunplanetdealz.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Discos duros s\u00f3lidos externos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sunplanetdealz.com\\\/#website\",\"url\":\"https:\\\/\\\/sunplanetdealz.com\\\/\",\"name\":\"Ofertas para el Verano en Sunplanetdealz\",\"description\":\"Encuentra las mejores ofertas para este verano, chollos irrepetibles en sunplanetdealz.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sunplanetdealz.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Discos duros s\u00f3lidos externos archivos - Ofertas para el Verano en Sunplanetdealz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/sunplanetdealz.com\/index.php\/categoria-producto\/discos-duros-solidos-externos\/","og_locale":"es_ES","og_type":"article","og_title":"Discos duros s\u00f3lidos externos archivos - Ofertas para el Verano en Sunplanetdealz","og_url":"http:\/\/sunplanetdealz.com\/index.php\/categoria-producto\/discos-duros-solidos-externos\/","og_site_name":"Ofertas para el Verano en Sunplanetdealz","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/sunplanetdealz.com\/index.php\/categoria-producto\/discos-duros-solidos-externos\/","url":"http:\/\/sunplanetdealz.com\/index.php\/categoria-producto\/discos-duros-solidos-externos\/","name":"Discos duros s\u00f3lidos externos archivos - Ofertas para el Verano en Sunplanetdealz","isPartOf":{"@id":"https:\/\/sunplanetdealz.com\/#website"},"breadcrumb":{"@id":"http:\/\/sunplanetdealz.com\/index.php\/categoria-producto\/discos-duros-solidos-externos\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"http:\/\/sunplanetdealz.com\/index.php\/categoria-producto\/discos-duros-solidos-externos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/sunplanetdealz.com\/"},{"@type":"ListItem","position":2,"name":"Discos duros s\u00f3lidos externos"}]},{"@type":"WebSite","@id":"https:\/\/sunplanetdealz.com\/#website","url":"https:\/\/sunplanetdealz.com\/","name":"Ofertas para el Verano en Sunplanetdealz","description":"Encuentra las mejores ofertas para este verano, chollos irrepetibles en sunplanetdealz.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sunplanetdealz.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"http:\/\/sunplanetdealz.com\/index.php\/wp-json\/wp\/v2\/product_cat\/1730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/sunplanetdealz.com\/index.php\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"http:\/\/sunplanetdealz.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"http:\/\/sunplanetdealz.com\/index.php\/wp-json\/wp\/v2\/product?product_cat=1730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}